{"id":14019,"date":"2022-08-25T07:30:51","date_gmt":"2022-08-25T10:30:51","guid":{"rendered":"https:\/\/obeabadosertao.com.br\/portal\/?p=14019"},"modified":"2022-08-25T14:13:02","modified_gmt":"2022-08-25T17:13:02","slug":"estatua-de-frei-damiao-e-o-primeiro-monumento-do-frade-capuchinho","status":"publish","type":"post","link":"https:\/\/obeabadosertao.com.br\/portal\/2022\/08\/25\/estatua-de-frei-damiao-e-o-primeiro-monumento-do-frade-capuchinho\/","title":{"rendered":"Sousa (PB) tem o primeiro monumento de Frei Dami\u00e3o na Para\u00edba"},"content":{"rendered":"<div id=\"tt-temp-estim\">Tempo de leitura: 4 minutos<\/div><p>A est\u00e1tua de <strong>Frei Dami\u00e3o<\/strong> no munic\u00edpio de Sousa, sert\u00e3o paraibano, \u00e9 o primeiro grande monumento na Para\u00edba em alus\u00e3o \u00e0 religiosidade e ao turismo religioso referente ao famoso frade capuchinho que peregrinou por anos pelas cidades nordestinas.<\/p>\n<div class=\"fopa-ad-intext\">Medindo 6,5 metros de altura, a est\u00e1tua fica distante 6,5 quil\u00f4metros do centro da cidade de Sousa. A imagem \u00e9 uma obra do escultor pernambucano <strong>Abelardo da Hora<\/strong>. Constru\u00edda na localidade chamada de Alto da B\u00ean\u00e7\u00e3o de Deus, recebe muitos fi\u00e9is ao longo do ano. H\u00e1 quase 50 anos, mais especificamente em 1975, Frei Dami\u00e3o recebeu a medalha de ouro de \u2018<em>Amigo da Cidade de Sousa<\/em>\u2019.<\/div>\n<div><\/div>\n<div><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=svfvZXL1sQaZPLgec1HYKZdcUR9en33y\" width=\"700\" height=\"500\" \/><\/div>\n<div class=\"fopa-ad-intext\">\n<p>Na \u00e9poca, ele permitiu que fosse constru\u00edda a primeira est\u00e1tua em sua homenagem e foi, inclusive, o pr\u00f3prio religioso o respons\u00e1vel por colocar a pedra fundamental do monumento. J\u00e1 em 1976, no m\u00eas de novembro, celebrou a missa de inaugura\u00e7\u00e3o. A escritora Porcina Furtado, que \u00e9 natural do munic\u00edpio de Sousa, relata que a est\u00e1tua recebe visitas de turistas de v\u00e1rias localidades, mas n\u00e3o disp\u00f5e de uma estrutura adequada para receber os fi\u00e9is locais ou turistas, a exemplo de museu ou restaurante.<\/p>\n<p>Ela afirma ainda que a respons\u00e1vel pela organiza\u00e7\u00e3o das missas e peregrina\u00e7\u00f5es \u00e9 a <strong>Igreja S\u00e3o Jo\u00e3o Batista<\/strong>. No local, \u00e9 realizada uma missa mensal, sempre no \u00faltimo domingo, \u00e0s 6h. H\u00e1 tamb\u00e9m uma peregrina\u00e7\u00e3o anual no anivers\u00e1rio de morte de Frei Dami\u00e3o saindo da Igreja S\u00e3o Jo\u00e3o Batista, \u00e0s 4h, em dire\u00e7\u00e3o ao monumento que, conforme a escritora, n\u00e3o \u00e9 tombado por nenhum \u00f3rg\u00e3o.<\/p>\n<p><em>\u201cEm conversa com algumas pessoas sobre a import\u00e2ncia da est\u00e1tua de Frei Dami\u00e3o, verifiquei que ela representa a figura do frei e a f\u00e9, especialmente em per\u00edodos de seca, quando ele visitava com frequ\u00eancia o Sert\u00e3o\u201d<\/em>, destaca Porcina Furtado.<\/p>\n<p>O historiador Jos\u00e9 Oct\u00e1vio de Arruda Melo relata que a constru\u00e7\u00e3o da est\u00e1tua de Frei Dami\u00e3o foi uma iniciativa da prefeitura da cidade na \u00e9poca. <em>\u201cFrei Dami\u00e3o \u00e9 muito conceituado no interior. As pessoas, literalmente, trocavam a religi\u00e3o cat\u00f3lica por Frei Dami\u00e3o. Por conta disso, foram criadas as est\u00e1tuas do frei\u201d<\/em>, declara, ressaltando que a existente em Guarabira \u00e9 a mais famosa da Para\u00edba. <em>\u201cA cidade de Sousa reparte muito Frei Dami\u00e3o com a hist\u00f3ria do Parque dos Dinossauros\u201d.<\/em> Guarabira n\u00e3o tem essa alternativa e, por isso, a manifesta\u00e7\u00e3o \u00e9 maior l\u00e1, atraindo gente da Para\u00edba e dos estados vizinhos, como Rio Grande do Norte, Alagoas e Pernambuco.<\/p>\n<p>A Prefeitura Municipal de Sousa (PMS) elaborou projeto para a constru\u00e7\u00e3o de um santu\u00e1rio no local onde foi erguida a est\u00e1tua de Frei Dami\u00e3o. A proposta, conforme o turism\u00f3logo Silvonetto Oliveira da Silva, que \u00e9 do quadro da prefeitura da cidade, foi apresentada \u00e0 Diocese de Cajazeiras que \u00e9 a institui\u00e7\u00e3o respons\u00e1vel pela manuten\u00e7\u00e3o do monumento, mas ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es se a ideia vai ser concretizada.<\/p>\n<p><em>\u201cPor parte da prefeitura, n\u00e3o temos prazo para a constru\u00e7\u00e3o do santu\u00e1rio, haja vista que a Diocese n\u00e3o cedeu o local para a constru\u00e7\u00e3o\u201d<\/em>, declara o secret\u00e1rio do Turismo de Sousa, Fernando Macena da Cruz.<\/p>\n<p>Segundo ele, a informa\u00e7\u00e3o mais recente \u00e9 de que o santu\u00e1rio seria constru\u00eddo com recursos pr\u00f3prios da Diocese. Enquanto o santu\u00e1rio n\u00e3o \u00e9 constru\u00eddo, os fi\u00e9is mant\u00eam a visita\u00e7\u00e3o \u00e0 est\u00e1tua de Frei Dami\u00e3o todos os domingos pela manh\u00e3 para rezar o ter\u00e7o, e no \u00faltimo domingo do m\u00eas \u00e9 realizada uma missa com a presen\u00e7a de padres, ministros da eucaristia, frades e demais religiosos. O lugar \u00e9 um dos principais s\u00edmbolos de f\u00e9 e religiosidade crist\u00e3 da comunidade cat\u00f3lica no Alto Sert\u00e3o paraibano, onde frequentemente \u00e9 registrada a presen\u00e7a de romeiros e peregrinos que se dirigem \u00e0 est\u00e1tua para ora\u00e7\u00f5es e pagamentos de promessa pelas gra\u00e7as e milagres atribu\u00eddos a Frei Dami\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #000080;\">Hist\u00f3ria<\/span><\/h2>\n<p>Nascido <strong>Pio Giannotti<\/strong>, em Bozzano (It\u00e1lia), no dia 5 de novembro de 1898, Frei Dami\u00e3o recebeu, aos 17 anos, o h\u00e1bito de capuchinho, sendo nomeado <strong>Frei Dami\u00e3o de Bozzano<\/strong>. Come\u00e7ou a peregrina\u00e7\u00e3o e evangeliza\u00e7\u00e3o pelo Nordeste em 1931. Morreu em Recife (PE), em 31 de maio de 1997, de insufici\u00eancia respirat\u00f3ria, aos 98 anos. Al\u00e9m de sua import\u00e2ncia hist\u00f3rica e de interesse dos seguidores do religioso capuchinho, a est\u00e1tua a Frei Dami\u00e3o na cidade de Sousa se torna ainda mais de destaque pela autoria da obra de arte.<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=fHUIJf5lxj1wr41rB1WDrzpzuC3TleSs\" width=\"700\" height=\"500\" \/><\/p>\n<\/div>\n<h2><\/h2>\n<h2><span style=\"color: #000080;\">Abelardo Hora<\/span><\/h2>\n<div class=\"fopa-ad-intext\">\n<p>O monumento \u00e9 assinado por um dos mais importantes escultores das artes pl\u00e1sticas do Brasil: Abelardo Germano da Hora, pernambucano de S\u00e3o Louren\u00e7o da Mata, nascido em 31 de julho de 1924, e que morreu aos 90 anos, em Recife, a 23 de setembro de 2014. Abelardo da Hora foi um artista pl\u00e1stico, professor, poeta, escultor, desenhista, gravurista, pintor e ceramista. Era formado em Artes Pl\u00e1sticas pela Escola de Belas Artes de Recife e em Direito pela Faculdade de Direito de Olinda.<\/p>\n<p><img decoding=\"async\" class=\"size-full aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=bZhN9Dc1HStAwNgLUc3tmTA5kCqSkfPc\" width=\"700\" height=\"500\" \/><\/p>\n<div class=\"post-footer clearfix\">\n<div class=\"post-tag-container\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tempo de leitura: 4 minutosA est\u00e1tua de Frei Dami\u00e3o no munic\u00edpio de Sousa, sert\u00e3o paraibano, \u00e9 o primeiro grande monumento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,40],"tags":[6335,5412,6336,6337,6348,6334,6342,6350,6346,6333,2591,6338,621,6339,5007,14,6340,2522,4263,6347,598,6341,5008,1710,6349,5376,6344,2592,6345,6343],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/14019"}],"collection":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/comments?post=14019"}],"version-history":[{"count":5,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/14019\/revisions"}],"predecessor-version":[{"id":14025,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/14019\/revisions\/14025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/media\/14021"}],"wp:attachment":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/media?parent=14019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/categories?post=14019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/tags?post=14019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}