{"id":17903,"date":"2023-09-03T08:27:02","date_gmt":"2023-09-03T11:27:02","guid":{"rendered":"https:\/\/obeabadosertao.com.br\/portal\/?p=17903"},"modified":"2023-09-02T16:25:28","modified_gmt":"2023-09-02T19:25:28","slug":"hibrido-de-humano-e-chimpanze-existiu-e-foi-morto-por-medicos-garante-cientista","status":"publish","type":"post","link":"https:\/\/obeabadosertao.com.br\/portal\/2023\/09\/03\/hibrido-de-humano-e-chimpanze-existiu-e-foi-morto-por-medicos-garante-cientista\/","title":{"rendered":"H\u00edbrido de Humano e Chimpanz\u00e9 existiu e foi morto por m\u00e9dicos, garante cientista"},"content":{"rendered":"<div id=\"tt-temp-estim\">Tempo de leitura: 2 minutos<\/div><h3><span style=\"color: #000080;\"><em><strong>Criatura nomeada &#8216;humanzee&#8217; foi feita por meio de insemina\u00e7\u00e3o artificial; segundo evolucionista, ela nasceu nos EUA e foi morta pela pr\u00e1tica eutan\u00e1sia.<\/strong><\/em><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p>Um cientista renomado fez uma afirma\u00e7\u00e3o que deixou o mundo da ci\u00eancia euf\u00f3rico. O psic\u00f3logo evolutivo, Gordon Gallup, relatou que, quase 100 anos atr\u00e1s, um h\u00edbrido humano-chimpanz\u00e9 foi criado em um laborat\u00f3rio nos Estados Unidos.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=FxbeSgJZlztbSAWjKp1y7eldN7GZEACH\" width=\"700\" height=\"500\" \/><\/p>\n<p>Segundo Gallup, um de seus professores confirmou que o\u00a0h\u00edbrido\u00a0conhecido como &#8216;<em>humanzee&#8217;<\/em>\u00a0\u00a0foi gerado em Orange Park, na Fl\u00f3rida, em 1920, por\u00e9m foi morto depois que m\u00e9dicos entraram em p\u00e2nico com o seu\u00a0 desenvolvimento.<\/p>\n<p><img decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=lYdgh2mNrw07DYyk8SQetJqPYCrmUObe\" width=\"700\" height=\"500\" \/><\/p>\n<p>\u201c<em>Eles inseminaram uma chimpanz\u00e9 f\u00eamea com s\u00eamen humano de um doador n\u00e3o revelado. A gravidez passou por todas as etapas, permitindo que um beb\u00ea metade humano e metade macaco nascesse. Seus dias na Terra n\u00e3o duraram muito devido as considera\u00e7\u00f5es morais e \u00e9ticas de alguns m\u00e9dicos, que decidiram aplicar o m\u00e9todo eutan\u00e1sia nele<\/em>\u201d, diz.<\/p>\n<p><img decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=lLkUjVDDdhgTf53L3rcBUNd9vcVlycXR\" width=\"700\" height=\"500\" \/><\/p>\n<p>Gallup exp\u00f5e que n\u00e3o pode revelar quem lhe contou sobre o &#8216;<em>humanzee<\/em>&#8216;, mas garante se tratar de um &#8220;<em>profissional muito conhecido<\/em>&#8220;, que trabalhou na Yerkes e no centro de pesquisa da Universidade Emory, em Atlanta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=lZf6RC4aD72oDPpl5YdK1tsYV6cvmO5O\" width=\"700\" height=\"500\" \/><\/p>\n<p>Vale lembrar que os exemplos mais antigos e not\u00e1veis de hibridiza\u00e7\u00e3o humano-macaco foram testados em 1920, pelo cientista russo <strong>Ilya Ivanovich Ivanov<\/strong> (bi\u00f3logo russo, especialista em insemina\u00e7\u00e3o artificial e hibrida\u00e7\u00e3o interespec\u00edfica de animais).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=jpXPUoBdyERysAymxDBKYxXv1h2kAaey\" width=\"700\" height=\"500\" \/><\/p>\n<p>Seus experimentos tamb\u00e9m foram feitos por insemina\u00e7\u00e3o artificial, por\u00e9m n\u00e3o obtiveram sucesso.<\/p>\n<p>Com isso, ele criou v\u00e1rias outras pr\u00e1ticas controversas envolvendo esperma de macaco e volunt\u00e1rias humanas. O projeto foi interrompido e nunca foi retomado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=eZEazglvT14d9szikHmYskfH6jR5dpYX\" width=\"700\" height=\"500\" \/><\/p>\n<p>Mais recentemente, em 1958, &#8220;<strong><em>Oliver, o chimpanz\u00e9<\/em><\/strong>&#8221; foi considerado um &#8216;<em>humanzee<\/em>&#8216; por causa de sua fei\u00e7\u00e3o e comportamento humanos.<\/p>\n<p>Ele andava sobre dois p\u00e9s, tinha nariz saliente e sardas por toda a face, o que aumentou ainda mais as especula\u00e7\u00f5es.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=O65RZvreOpHDGtnRtqJ9f4LXh1Txq8nk\" width=\"700\" height=\"500\" \/><\/p>\n<p>Entretanto, em 1996, um teste de DNA revelou que Oliver tinha 48 cromossomos, numera\u00e7\u00e3o comum de um chimpanz\u00e9.<\/p>\n<p>Para ser considerado um h\u00edbrido, deveria conter 47, que fica entre os 48 de um chimpanz\u00e9 e 46, de um humano. <strong>Oliver<\/strong> morreu em 2012, aos 55 anos de idade.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=7p9pPHbCjJavwSgqXc71lUTr8OKf7UKp\" width=\"700\" height=\"500\" \/><\/p>\n<p>O psic\u00f3logo afirma que, al\u00e9m dos chimpanz\u00e9s, \u00e9 poss\u00edvel criar um\u00a0h\u00edbrido cruzando humanos com gorilas e orangotangos, mas que \u00e9 pouco prov\u00e1vel que\u00a0experimentos futuros\u00a0para a cria\u00e7\u00e3o dos &#8216;<em>hurilla<\/em>&#8216; e &#8216;<em>hurang<\/em>\u2019 superem os custos grandiosos que podem acarretar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempo de leitura: 2 minutosCriatura nomeada &#8216;humanzee&#8217; foi feita por meio de insemina\u00e7\u00e3o artificial; segundo evolucionista, ela nasceu nos EUA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,29,6],"tags":[16487,16473,16482,4425,16478,632,41,16506,9722,16477,16488,16472,16471,16470,16474,16476,16480,16483,16485,16475,16484,16486,16481,16479],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/17903"}],"collection":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/comments?post=17903"}],"version-history":[{"count":3,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/17903\/revisions"}],"predecessor-version":[{"id":17906,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/17903\/revisions\/17906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/media\/17907"}],"wp:attachment":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/media?parent=17903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/categories?post=17903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/tags?post=17903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}