{"id":19877,"date":"2024-06-01T08:25:05","date_gmt":"2024-06-01T11:25:05","guid":{"rendered":"https:\/\/obeabadosertao.com.br\/portal\/?p=19877"},"modified":"2024-05-29T15:22:26","modified_gmt":"2024-05-29T18:22:26","slug":"cigarro-pode-ser-taxado-em-250-e-bebidas-alcoolicas-em-ate-61","status":"publish","type":"post","link":"https:\/\/obeabadosertao.com.br\/portal\/2024\/06\/01\/cigarro-pode-ser-taxado-em-250-e-bebidas-alcoolicas-em-ate-61\/","title":{"rendered":"Cigarro pode ser taxado em 250% e bebidas alco\u00f3licas em at\u00e9 61%"},"content":{"rendered":"<div id=\"tt-temp-estim\">Tempo de leitura: 4 minutos<\/div><h3><span style=\"color: #000080;\"><em><strong>Al\u00e9m do cigarro, o Banco Mundial considerou uma taxa de 32,9% para os refrigerantes; 46,3% para cerveja e chope; 61,6% para outras bebidas alco\u00f3licas.<\/strong><\/em><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p>Uma ferramenta desenvolvida pelo Banco Mundial traz a estimativa das al\u00edquotas do Imposto Seletivo, o chamado \u201c<em>imposto do pecado<\/em>\u201d, que incidir\u00e1 sobre itens considerados nocivos \u00e0 sa\u00fade e ao ambiente, entre eles, o cigarro.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=pQxYZyfwrrrCWJSDiJh5bzSF6JV0bmun\" width=\"700\" height=\"500\" \/><\/p>\n<p>Trata-se de um dos pontos de maior diverg\u00eancia na regulamenta\u00e7\u00e3o da reforma tribut\u00e1ria, que come\u00e7ar\u00e1 a ser analisada por um grupo de trabalho na C\u00e2mara dos Deputados.<\/p>\n<p>O organismo internacional, que acompanha de perto a mudan\u00e7a nos tributos brasileiros e seus impactos distributivos, considerou uma taxa de 32,9% para os refrigerantes; 46,3% para cerveja e chope; 61,6% para outras bebidas alco\u00f3licas; e 250% no caso dos cigarros.<\/p>\n<p><img decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=NQOicZxFK6fmcggQRHe3eeNAisDa2Mzj\" width=\"700\" height=\"500\" \/><\/p>\n<p>Esses percentuais foram projetados pelo banco com base em informa\u00e7\u00f5es repassadas pelo Minist\u00e9rio da Fazenda, mas n\u00e3o refletem as cobran\u00e7as exatas do Seletivo, que t\u00eam particularidades conforme o produto, e s\u00f3 ser\u00e3o definidas futuramente, por meio de lei ordin\u00e1ria.<\/p>\n<p>Em nota, a secretaria Extraordin\u00e1ria da Reforma Tribut\u00e1ria afirma que repassou aos economistas do banco as al\u00edquotas consideradas pela equipe de quantifica\u00e7\u00e3o, as quais t\u00eam o objetivo de manter a carga tribut\u00e1ria desses produtos.<\/p>\n<p><img decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=PQYxfMfFyZyNKuHIlklS2WjgGnlCR45m\" width=\"700\" height=\"500\" \/><\/p>\n<p>Os t\u00e9cnicos da Fazenda frisaram, por\u00e9m, que se trata de \u201c<em>hip\u00f3teses de trabalho<\/em>\u201d. O objetivo dos economistas do banco foi dar uma dimens\u00e3o a essas cobran\u00e7as e, assim, viabilizar simula\u00e7\u00f5es no \u00e2mbito do novo sistema tribut\u00e1rio &#8211; que ter\u00e1 uma segunda guerra de lobbies no Congresso.<\/p>\n<p>Tributaristas alertam que essa fase de regulamenta\u00e7\u00e3o da reforma ser\u00e1 ainda mais intricada e delicada do que o texto da Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC), promulgado no ano passado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=OnOrZNJ1cKxsVS0AoT0cWk9qeu9W086A\" width=\"700\" height=\"500\" \/><\/p>\n<p>Cada v\u00edrgula, das 360 p\u00e1ginas da lei complementar, poder\u00e1 ter impacto na al\u00edquota final do Imposto sobre Valor Agregado (o IVA, que unificar\u00e1 cinco tributos).<\/p>\n<p>Por isso, a aposta do banco na cria\u00e7\u00e3o da ferramenta, que foi batizada de Simulador de Imposto sobre Valor Agregado (SimVat, na sigla em ingl\u00eas).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=r3oeoeD3m6SOKezqMxQ6XlU1IwLOTITn\" width=\"700\" height=\"500\" \/><\/p>\n<p>A inten\u00e7\u00e3o do organismo \u00e9 de que pesquisadores, parlamentares e contribuintes testem os efeitos de eventuais altera\u00e7\u00f5es na lei.<\/p>\n<p>\u201c<em>Ao lan\u00e7ar o SimVat, o Banco Mundial enfatiza a import\u00e2ncia de usar evid\u00eancias concretas e sugest\u00f5es baseadas em dados para inspirar o texto final da reforma<\/em>\u201d, diz Shireen Mahdi, economista principal da entidade para o Brasil.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=NdIjzf4CVm1mHFt0Jrj6SfV6S1NYk4NC\" width=\"700\" height=\"500\" \/><\/p>\n<p>A ferramenta mostra, por exemplo, que, caso n\u00e3o haja incid\u00eancia de Seletivo sobre bebidas alco\u00f3licas, refrigerantes e cigarros, a al\u00edquota-padr\u00e3o do novo IVA passaria de 26,5% para 28,1%.<\/p>\n<p>A Fazenda tem destacado que o imposto do \u201c<em>pecado<\/em>\u201d n\u00e3o tem fins arrecadat\u00f3rios, e sim regulat\u00f3rios &#8211; de combater h\u00e1bitos de consumo nocivos \u00e0 sa\u00fade e ao ambiente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=Vf6tIPPBk6D1aN1swzimHGbJsyCoQH0j\" width=\"700\" height=\"500\" \/><\/p>\n<p>No entanto, como uma das premissas da reforma \u00e9 ser fiscalmente neutra, mantendo a carga tribut\u00e1ria vigente, todo o sistema est\u00e1 inevitavelmente interligado.<\/p>\n<p>Logo, se a cobran\u00e7a \u00e9 reduzida em uma ponta, ela tem de aumentar em outra para compensar.<\/p>\n<h2><span style=\"color: #000080;\"><strong>Cesta b\u00e1sica<\/strong><\/span><\/h2>\n<p>No caso da cesta b\u00e1sica, outro tema controverso, o SimVat mostra que novas amplia\u00e7\u00f5es da lista, combinadas com a elimina\u00e7\u00e3o do cashback (devolu\u00e7\u00e3o de imposto aos mais pobres), podem ser uma maneira ineficiente de ajudar os mais vulner\u00e1veis.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=05lNTFBcFsEjqCUekjfleRCzEQ3XfWaW\" width=\"700\" height=\"500\" \/><\/p>\n<p>Se a isen\u00e7\u00e3o fosse estendida a todos os alimentos e n\u00e3o houvesse o cashback, a al\u00edquota do IVA, segundo a plataforma, aumentaria de 26,5% para 28,3%.<\/p>\n<p>Nesse caso, os 10% mais ricos da popula\u00e7\u00e3o teriam um leve aumento de carga tribut\u00e1ria, que passaria de 8,2% para 8,3%, como propor\u00e7\u00e3o da renda. J\u00e1 os 10% mais pobres veriam a sua taxa\u00e7\u00e3o saltar de 22,1% para 25,3%.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=iaO1C93mZFkhun09nMpxcl9pVvsTLX8O\" width=\"700\" height=\"500\" \/><\/p>\n<p>\u201c<em>Com dados oportunos e valiosos, os formuladores de pol\u00edticas podem tomar decis\u00f5es informadas que t\u00eam grandes impactos, especialmente para popula\u00e7\u00f5es vulner\u00e1veis<\/em>\u201d, diz Shireen, do Banco Mundial.<\/p>\n<h2><span style=\"color: #000080;\"><strong>Embate<\/strong><\/span><\/h2>\n<p>A cesta b\u00e1sica, no entanto, \u00e9 um ponto de embate entre setores e para o qual ainda n\u00e3o h\u00e1 consenso no \u00e2mbito do Congresso Nacional.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=UrHz5wQ7XGDSr9hxggxn4NcpupuNRqWc\" width=\"700\" height=\"500\" \/><\/p>\n<p>Os supermercados e o agroneg\u00f3cio, por exemplo, n\u00e3o abrem m\u00e3o de incluir as carnes na lista do imposto zero, e j\u00e1 iniciaram conversas com parlamentares para viabilizar essa altera\u00e7\u00e3o.<\/p>\n<p>O argumento \u00e9 de que a prote\u00edna animal pode acabar saindo de vez da dieta dos mais pobres.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=aV3AvQUu7PjaVo9BFCrboCIAtV0ydZVz\" width=\"700\" height=\"500\" \/><\/p>\n<p>Pelo projeto do governo, as carnes foram enquadradas na al\u00edquota reduzida, com desconto de 60% da padr\u00e3o, \u00e0 exce\u00e7\u00e3o de alguns itens considerados de luxo, que pagar\u00e3o al\u00edquota cheia.<\/p>\n<p>A Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI), por sua vez, vai na dire\u00e7\u00e3o contr\u00e1ria e j\u00e1 firmou posi\u00e7\u00e3o contr\u00e1ria \u00e0 amplia\u00e7\u00e3o da lista de produtos com al\u00edquota zero ou com tributa\u00e7\u00e3o reduzida, como os itens que integram a cesta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=dwdK5kBZDckpJWCkcgeRwifa1PJdk7wf\" width=\"700\" height=\"500\" \/><\/p>\n<p>A preocupa\u00e7\u00e3o \u00e9 exatamente com um eventual aumento da al\u00edquota-padr\u00e3o. \u201c<em>N\u00e3o vamos sugerir nenhuma inclus\u00e3o porque o que a gente quer \u00e9 que a al\u00edquota de refer\u00eancia seja a menor poss\u00edvel, que \u00e9 onde todo mundo vai pagar<\/em>\u201d, afirmou o superintendente de Economia da CNI, M\u00e1rio S\u00e9rgio Telles.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium aligncenter\" src=\"https:\/\/obeabadosertao.com.br\/filerun\/wl\/?id=AuK2vKCjwKXmtWBzGNNpD2GN359EppUo\" width=\"700\" height=\"500\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempo de leitura: 4 minutosAl\u00e9m do cigarro, o Banco Mundial considerou uma taxa de 32,9% para os refrigerantes; 46,3% para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,43,6],"tags":[23114,7302,291,6084,2448,23117,2447,23116,23112,15904,15903,23119,23110,8134,2088,1557,15894,23113,23111,23118,23109,23115],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/19877"}],"collection":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/comments?post=19877"}],"version-history":[{"count":1,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/19877\/revisions"}],"predecessor-version":[{"id":19878,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/19877\/revisions\/19878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/media\/19879"}],"wp:attachment":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/media?parent=19877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/categories?post=19877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/tags?post=19877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}