{"id":8253,"date":"2015-03-19T00:00:00","date_gmt":"2015-03-19T00:00:00","guid":{"rendered":""},"modified":"2015-03-19T00:00:00","modified_gmt":"2015-03-19T00:00:00","slug":"Ministro-da-educacao-manda-deputados-largarem-o-osso-e-pede-demissao","status":"publish","type":"post","link":"https:\/\/obeabadosertao.com.br\/portal\/2015\/03\/19\/Ministro-da-educacao-manda-deputados-largarem-o-osso-e-pede-demissao\/","title":{"rendered":"Ministro da educa\u00e7\u00e3o manda deputados largarem o osso e pede demiss\u00e3o"},"content":{"rendered":"<div id=\"tt-temp-estim\">Tempo de leitura: 14 minutos<\/div><p style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\n<span style=\"color: rgb(255, 0, 0);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><em><strong>&quot;Larguem o osso, saiam do governo&quot;, diz Cid a &quot;oportunistas&quot; na C&acirc;mara. Ministro da Educa&ccedil;&atilde;o foi convocado por deputados a dar explica&ccedil;&otilde;es. No dia 27, no Par&aacute;, ele disse que C&acirc;mara tem 300 a 400 que &quot;achacam&quot;.<\/strong><\/em><\/span><\/span><\/span><\/p>\n<p>\n<strong>Bras&iacute;lia(DF) &#8211; <\/strong>O ministro da Educa&ccedil;&atilde;o, Cid Gomes, pediu demiss&atilde;o nesta quarta-feira(<span style=\"font-family: Arial;\">18Mar&ccedil;o2015<\/span>) &agrave; presidente Dilma Rousseff. A informa&ccedil;&atilde;o foi confirmada oficialmente pela Casa Civil. A sa&iacute;da dele ocorreu ap&oacute;s uma fala do ministro na C&acirc;mara ter gerado revolta entre parlamentares na base aliada.<\/p>\n<p>\nConvocado pelo Legislativo para explicar uma declara&ccedil;&atilde;o dada por ele no in&iacute;cio do m&ecirc;s na Universidade Federal do Par&aacute;, Cid Gomes disse na tribuna do plen&aacute;rio da C&acirc;mara nesta quarta-feira que &quot;<em>partidos de oposi&ccedil;&atilde;o t&ecirc;m o dever de fazer oposi&ccedil;&atilde;o<\/em>&quot;. &quot;<em>Partidos de situa&ccedil;&atilde;o t&ecirc;m o dever de ser situa&ccedil;&atilde;o ou ent&atilde;o larguem o osso, saiam do governo<\/em>&quot;, disse.<\/p>\n<p><\/span><\/span><img fetchpriority=\"high\" decoding=\"async\" src=\"\/UserFiles\/Image\/politicos\/cid_ferreira_gomes_465.jpg\" width=\"465\" height=\"311\" align=\"absMiddle\" alt=\"\" style=\"font-family: Verdana; font-size: small;\" \/><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><\/p>\n<p>Em seguida, o ministro atacou o presidente da C&acirc;mara, Eduardo Cunha(<span style=\"font-family: Arial;\">PMDB-RJ<\/span>). &quot;<em>Prefiro ser acusado por ele(<span style=\"font-family: Arial;\">Cunha<\/span>) de mal-educado do que ser acusado como ele de achaque<\/em>&quot;, disse Cid, apontando para a Mesa Diretora, onde estava o presidente da Casa.<\/p>\n<p><\/span><\/span><img decoding=\"async\" src=\"\/UserFiles\/Image\/politicos\/deputado_federal_rj_eduardo_cosentino_da_cunha_465b.jpg\" width=\"465\" height=\"311\" align=\"absMiddle\" alt=\"\" style=\"font-family: Verdana; font-size: small;\" \/><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><\/p>\n<p>Pouco antes da confirma&ccedil;&atilde;o da sa&iacute;da de Cid do minist&eacute;rio, o PMDB havia amea&ccedil;ado romper com o governo caso o ministro n&atilde;o fosse demitido. Assim que deixou o pr&eacute;dio do Legislativo, o ministro foi chamado para uma conversa com a presidente Dilma Rousseff. Antes da confirma&ccedil;&atilde;o oficial de sua sa&iacute;da, Eduardo Cunha j&aacute; havia informado a imprensa que Cid havia ca&iacute;do.<\/p>\n<p><\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">&nbsp;<\/p>\n<p>No in&iacute;cio da noite, em uma nota de quatro linhas, o Planalto agradeceu a perman&ecirc;ncia de Gomes no cargo. &quot;<em>A presidenta agradeceu a dedica&ccedil;&atilde;o do ministro &agrave; frente da pasta<\/em>&quot;, diz o texto.<\/p>\n<p>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\n<span style=\"color: rgb(0, 0, 255);\"><strong><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\">Declara&ccedil;&otilde;es no Par&aacute;<\/span><\/span><\/strong><\/span><br \/>\nO pedido de explica&ccedil;&otilde;es da C&acirc;mara surgiu ap&oacute;s uma declara&ccedil;&atilde;o do ministro para professores e reitores durante uma visita &agrave; Universidade Federal do Par&aacute;. Um &aacute;udio com a fala do ministro, capturada no dia 27 de fevereiro, foi publicado no dia 4 deste m&ecirc;s, no Blog do Josias, do UOL.<br \/>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">&nbsp;<br \/>\n&quot;<em>Tem l&aacute; uns 400 deputados, 300 deputados que quanto pior melhor para eles. Eles querem &eacute; que o governo esteja fr&aacute;gil porque &eacute; a forma de eles achacarem mais, tomarem mais, tirarem mais dele, aprovarem as emendas impositivas<\/em>&quot;.<\/p>\n<p><\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> <span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>&quot;Menino mimado&quot;<\/strong><\/span><\/span><\/span><br \/>\nA fala de Cid desta tarde incomodou e foi criticada por v&aacute;rios parlamentares. Alguns deles chegaram a recomendar sua sa&iacute;da na tribuna.&nbsp;Pouco depois, ao retomar a fala, Cid fez novas acusa&ccedil;&otilde;es e abandonou o plen&aacute;rio da C&acirc;mara, quando foi acusado de fazer &quot;<em>papel de palha&ccedil;o<\/em>&quot; pelo deputado S&eacute;rgio Zveiter(<span style=\"font-family: Arial;\">PSD-RJ<\/span>), partido da base aliada.<\/p>\n<p>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">Ap&oacute;s a demiss&atilde;o, o l&iacute;der do PMDB na C&acirc;mara, Leonardo Picciani(<span style=\"font-family: Arial;\">RJ<\/span>), disse que Cid se comportou como &quot;<em>menino mimado<\/em>&quot;. &quot;<em>N&atilde;o esper&aacute;vamos outra atitude que n&atilde;o fosse essa. O que ele demonstrou aqui foi falta de forma&ccedil;&atilde;o democr&aacute;tica, de forma&ccedil;&atilde;o republicana. Ele saiu daqui como um fanfarr&atilde;o porque veio aqui, falou o que quis, ouviu o que n&atilde;o quis, saiu como menino mimado. Fiquei com uma p&eacute;ssima impress&atilde;o dele como homem p&uacute;blico. Agente incapaz de exercer a fun&ccedil;&atilde;o p&uacute;blica<\/em>&quot;, disse o l&iacute;der do PMDB ap&oacute;s a demiss&atilde;o de Cid.<\/p>\n<p>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">&nbsp;<br \/>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> <span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>Elei&ccedil;&otilde;es e minist&eacute;rio<\/strong><\/span><\/span><\/span><\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\nEx-integrante do PSB, Cid Gomes chegou ao minist&eacute;rio por ter se mantido fiel a Dilma Rousseff.&nbsp;Ele rejeitou a candidatura pr&oacute;pria do partido &agrave; Presid&ecirc;ncia &#8211; a legenda teve a ex-senadora Marina Silva como candidata ap&oacute;s a morte do ex-governador de Pernambuco Eduardo Campos. O grupo ligado a Cid Gomes, que inclui o irm&atilde;o Ciro Gomes, deixou o PSB em setembro de 2013 e se filiou ao Pros(<span style=\"font-family: Arial;\">Partido Republicano da Ordem Social<\/span>).<\/p>\n<p>\nO candidato dos Gomes, Camilo Santana(<span style=\"font-family: Arial;\">PT<\/span>), acabou se elegendo governador.  Santana foi secret&aacute;rio do Desenvolvimento Agr&aacute;rio e das Cidades durante a gest&atilde;o de Cid.<\/p>\n<p>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> <span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>Tempo real<\/strong><\/span><\/span><\/span><\/p>\n<p><strong>17h40min<\/strong><br \/>\nCid Gomes deixou o Plen&aacute;rio da Casa ap&oacute;s ser chamado de &quot;<em>palha&ccedil;o<\/em>&quot; pelo deputado do PSD.<\/p>\n<p>O presidente da C&acirc;mara Eduardo Cunha disse que n&atilde;o havia condi&ccedil;&otilde;es de manter a audi&ecirc;ncia &quot;<em>diante da postura de Cid<\/em>&quot;. &quot;<em>N&atilde;o vamos perder nosso dia trabalho por algu&eacute;m que n&atilde;o est&aacute; merecendo&quot;<\/em>, afirmou. Ele afirmou que acionar&aacute; a Justi&ccedil;a contra Cid Gomes.<\/p>\n<p><strong>17h32min<\/strong><br \/>\n&quot;<em>Achacar pode ser entendido como criar dificuldade para conseguir facilidade. Alguns querem criar mais dificuldade para conseguir mais minist&eacute;rios. Isso &eacute; disputa de poder at&eacute; certo ponto, normal numa democracia. Eu vim do nada e com nada eu vou. Sa&iacute; da minha pequena cidade de Sobral e a ela voltarei com a cabe&ccedil;a erguida. Aceitei ser ministro da Dilma porque confio nela, porque tenho convic&ccedil;&atilde;o de que ela &eacute; s&eacute;ria, bem intencionada e &eacute; v&iacute;tima de diversos setores da sociedade brasileira, dentre os quais pol&iacute;ticos, empres&aacute;rios. Me sinto livre de emitir opini&otilde;es. Como ministro, procurem uma declara&ccedil;&atilde;o minha que n&atilde;o tenha sido limitada &agrave; Educa&ccedil;&atilde;o<\/em>&quot;.<br \/>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> &quot;<em>N&atilde;o fui eu que procurei que essa frase fosse divulgada. Nunca fiz proselistismo disso. Eu n&atilde;o sou o Minist&eacute;rio P&uacute;blico que &eacute; uma institui&ccedil;&atilde;o &agrave; parte. &Eacute; o Minist&eacute;rio P&uacute;blico que tem o dever de investigar, procurar pessoas que agem em desrespeito ao parlamento<\/em>&quot;.<\/p>\n<p><strong>17h26min<\/strong><br \/>\nCid Gomes responde deputados: &quot;<em>Eu j&aacute; disse com todas as letras que tenho profundo respeito pela institui&ccedil;&atilde;o parlamento, acho fundmental que a gente tenha harmonia. Numa sala reservada emiti uma opini&atilde;o que n&atilde;o foi elaborada, que foi feita &agrave; quele momento e que diz, sem sofismas, sem discurso bonito, estou aqui com toda humildade em respeito a essa Casa, ao parlamento brasileiro. N&atilde;o tenho problema nenhum com quem tenha se julgado agredido injustamente. Adivulga&ccedil;&atilde;o foi feita por uma grava&ccedil;&atilde;o sem minha autoriza&ccedil;&atilde;o. Isso &eacute; uma prova nula. Vou repetir a frase de forma mais did&aacute;tica poss&iacute;vel<\/em>&quot;, disse Cid.<\/p>\n<p>Ele voltou a citar a situa&ccedil;&atilde;o em que pronunciou a fala contra os deputados: &quot;<em>Meus amigos estudantes, aprovar or&ccedil;amento n&atilde;o &eacute; uma quest&atilde;o que diga respeito s&oacute; ao Executivo, a abse do Executivo nem sempre est&aacute; comprometido com o que faz o Executivo<\/em>&quot;.<br \/>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> <\/p>\n<p><strong>17h08min<\/strong><br \/>\nO deputado cearense Cabo Sabino(<span style=\"font-family: Arial;\">PR<\/span>) reasgatou desanven&ccedil;as pol&iacute;ticas com Cid Gomes por causa de a&ccedil;&otilde;es na Pol&iacute;cia Militar. &quot;<em>Quando a Pol&iacute;cia fez press&atilde;o no senhor, o senhor n&atilde;o foi esse le&atilde;o que foi aqui, mas um gatinho encurralado pela categoria que maltratou durante sete anos<\/em>&quot;, disse Sabino.<\/p>\n<p><strong>17h00min<\/strong><br \/>\nO deputado Pompeo de Mattos, do PDT, criticou que os deputados levaram a crise pol&iacute;tica para dentro do parlamento. &quot;<em>Quero dizer ao ministro que n&oacute;s do PDT nos sentimos desculpados porque o PDT n&atilde;o achaca ningu&eacute;m, porque para n&oacute;s n&atilde;o serve a carapu&ccedil;a e n&oacute;s temos postura e dignidide<\/em>&quot;, disse Mattos.<br \/>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> <\/p>\n<p><strong>16h55min<\/strong><br \/>\nO l&iacute;der do Psol, Chico Alencar, leu os diversos significados da palavra &quot;<em>achacar<\/em>&quot;. &quot;O parlamento tem uma tradi&ccedil;&atilde;o no Brasil de esp&iacute;rito de porco, temos que reconhecer que o hist&oacute;rico da pol&iacute;tica brasileira tem a trajet&oacute;ria do &quot;<em>toma l&aacute; d&aacute; c&aacute;<\/em>&quot;. Ele citou a investiga&ccedil;&atilde;o da Lava Jato que atinge deputados da C&acirc;mara. &quot;<em>Isso &eacute; desastroso para a pr&oacute;pria imagem do parlamento, porque temos de discutir a educa&ccedil;&atilde;o, a sa&uacute;de<\/em>&quot;. &quot;<em>N&atilde;o me sinto &agrave; vontade em pedir que um ministro deixe um minist&eacute;rio porque isso n&atilde;o &eacute; nosso trabalho pol&iacute;tico<\/em>&quot;, disse Chico Alencar.<\/p>\n<p><strong>16h37min<\/strong><br \/>\nO l&iacute;der do PSC, Andr&eacute; Moura, defendeu tamb&eacute;m que Cid deixou de ter legalidade para ocupar o minist&eacute;rio. Ele relembrou epis&oacute;dio de Cid, enquanto governador do Cear&aacute;, de ter fretado aeronave com dinheiro p&uacute;blico para viajar com a fam&iacute;lia. Ele citou ainda a pol&ecirc;mica da obra do Acquario Cear&aacute;, do show da cantora Ivete Sangalo com cach&ecirc; superfaturado para inaugurar Hospital Regional Norte, em Sobral, e da marquise do mesmo hospital que caiu ap&oacute;s a inaugura&ccedil;&atilde;o. Ele chamou Cid de &quot;<em>mal-educado<\/em>&quot;, &quot;<em>desqualificado<\/em>&quot; e &quot;<em>achacador do Estado do Cear&aacute; e da sua gente<\/em>&quot;. Ele disse ainda que Cid tem &quot;<em>sorriso ir&ocirc;nico e c&iacute;nico<\/em>&quot;.<br \/>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> <\/p>\n<p><strong>16h32min<\/strong><br \/>\nO l&iacute;der do Pros, deputado cearense Domingos Neto, foi o primeiro a tentar defender o ex-governador Cid Gomes, seu correligion&aacute;rio. &quot;<em>Voc&ecirc; est&aacute; sendo v&iacute;tima do que a oposi&ccedil;&atilde;o tenta colocar nesse momento: tentar colocar nas costas da Dilma o que foi aqui falado<\/em>&quot;, disse Domingos. &quot;<em>Me guardo a pensar quais seriam os interesses envolvidos em mais uma vaga na Esplanada dos Minist&eacute;rios<\/em>&quot;.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">&quot;<em>Essa Casa quis fazer o gesto de mais uma vez tentar provocar o Governo e se colocar em situa&ccedil;&atilde;o de xeque<\/em>&quot;, disse o deputado. Ele ressaltou que Cid pediu desculpas sobre a fala e disse ter respeito pelo Parlamento.<\/p>\n<p><strong>16h28min<\/strong><br \/>\nO l&iacute;der do PSDB, deputado Bruno Ara&uacute;jo, pediu a sa&iacute;da de Cid Gomes do cargo de ministro da Educa&ccedil;&atilde;o.<\/p>\n<p><\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> <br \/>\n<strong>16h18min<\/strong><br \/>\nO deputado Artur Maia(<span style=\"font-family: Arial;\">SD<\/span>) discursou no Plen&aacute;rio. &quot;<em>Tenho 25 anos de mandato e esse &eacute; o momento mais constragedor que j&aacute; vi. O Brasil inteiro est&aacute; vendo um ministro de Estado vir ao parlamento para dizer que 400 dos parlamentares s&atilde;o criminosos, achacadores<\/em>&quot;. Ap&oacute;s questionar se o nome dele est&aacute; entre os citados por Cid como achacador, ele afirmou que o ministro j&aacute; havia respondido. &quot;<em>O senhor disse que os 300 ou 400 achacadores n&atilde;o est&atilde;o na oposi&ccedil;&atilde;o, mas na base da presidente Dilma que nomeou o senhor ministro da Rep&uacute;blica. Certamente nem a Dilma nem o Brasil precisaria dessa fala destemperada de vossa excel&ecirc;ncia<\/em>&quot;. &quot;<em>300 ou 400 deputados &eacute; praticamente toda a base do governo<\/em>&quot;.<\/p>\n<p><strong>16h07min<\/strong><br \/>\nO deputado Mendon&ccedil;a Filho(<span style=\"font-family: Arial;\">DEM<\/span>), autor do requerimento, disse que ou Cid renuncia, ou Dilma Rousseff o demite ou os deputados assumir&atilde;o que s&atilde;o &quot;<em>achacadores<\/em>&quot;. &quot;<em>Esse governo produz uma crise por dia para a gest&atilde;o da presidente<\/em>&quot;, disse Mendon&ccedil;a.<\/p>\n<p><\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> <strong>16h00min<\/strong><br \/>\nLeonardo Picciani disse que Cid perdeu a legitimidade para ocupar cargo de ministro e que os deputados cobrar&atilde;o do Governo uma resposta sobre a permiss&atilde;o aos seus ministros de desrespeitar o Legislativo.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\n<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">15h55min<\/span><\/span><\/strong><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\nO ministro esquece as regras de conviv&ecirc;ncia democr&aacute;tica, desrespeitou o parlamento de forma pueril e leviana, disse o l&iacute;der do PMDB, Eduardo Picciane, que pediu que Cid aponte o nome dos 300 achacadores.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><\/p>\n<p><strong>15h50min<\/strong><br \/>\nEduardo Cunha encerrou a fala de Cid Gomes e mandou retirar do plen&aacute;rio todos os que n&atilde;o sejam deputados federais. O governador do Cear&aacute;, Camilo Santana, o presidente da Assembleia Legislativa do Cear&aacute;, Zezinho Albuquerque, e o prefeito de Fortaleza, Roberto Cl&aacute;udio(<span style=\"font-family: Arial;\">Pros<\/span>), estavam no local.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"\/UserFiles\/Image\/politicos\/deputado_federal_rj_eduardo_cosentino_da_cunha_465a.jpg\" width=\"465\" height=\"311\" align=\"absMiddle\" alt=\"\" style=\"font-family: Verdana; font-size: small;\" \/><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><\/p>\n<p><br type=\"_moz\" \/><br \/>\n<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">15h45min<\/span><\/span><\/strong><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\nAo relatar problema de sa&uacute;de e criticar comiss&atilde;o de deputados para averiguar sua sa&uacute;de, Cid fez refer&ecirc;ncia direta ao presidente da Casa, Eduardo Cunha. Apontando ao presidente, Cid Gomes falou: &ldquo;<em>Prefiro ser acusado por ele de mal-educado do que ser acusado como ele de achaque, como diz a capa da Folha de S. Paulo<\/em>&rdquo;.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">O ministro da Educa&ccedil;&atilde;o disse que os parlamentares da base do governo que n&atilde;o votam de acordo com a orienta&ccedil;&atilde;o do Planalto devem &ldquo;<em>largar o osso<\/em>&rdquo; e ir para a oposi&ccedil;&atilde;o. &ldquo;<em>Partidos de oposi&ccedil;&atilde;o t&ecirc;m o dever de fazer oposi&ccedil;&atilde;o. Partidos de situa&ccedil;&atilde;o t&ecirc;m o dever de ser situa&ccedil;&atilde;o ou ent&atilde;o larguem o osso, saiam do governo<\/em>&rdquo;, afirmou.<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\n<\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">15h35min<\/span><\/span><\/strong><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\n&ldquo;<em>Me perdoem, eu n&atilde;o tenho nenhum problema em pedir perd&atilde;o aqueles que n&atilde;o agem dessa forma, para aqueles que se comportam desse jeito. N&atilde;o quis atingir ningu&eacute;m individualmente, muito menos a institui&ccedil;&atilde;o. O que penso e continuo pensando &eacute; que n&oacute;s conquistamos uma democracia com muita luta e muito sofrimento para poder fazer uso livre da sua manifesta&ccedil;&atilde;o da sua opini&atilde;o. Me perdoem se algu&eacute;m traz para si essa carapu&ccedil;a se algu&eacute;m se enxerga na posi&ccedil;&atilde;o<\/em>&rdquo;, disse Cid.<\/p>\n<p><span style=\"font-family: Verdana;\"><strong>15h30min<\/strong><\/span><br \/>\nAp&oacute;s ter o microfone cortado e retomar a fala, Cid foi mais direto: &ldquo;<em>Tenho respeito pelo Legislativo, pelo parlamento, mas que n&atilde;o quer dizer que concorde com a postura de alguns, de muitos que seus partidos, mesmo participando do governo, tenham uma postura aqui de oportunismo<\/em>&rdquo;, falou. Nesse momento, alguns deputados gritaram pedindo &ldquo;<em>respeito &agrave; Casa<\/em>&rdquo;.<\/p>\n<p><strong>15h15min<\/strong><br \/>\n&ldquo;<em>Quem falava naquele momento n&atilde;o era o ministro, era a pessoa f&iacute;sica, que tem grande respeito pela institui&ccedil;&atilde;o legislativa e compreende o papel fundamental do parlamento que foi onde eu comecei minha carreira pol&iacute;tica<\/em>&rdquo;, disse Cid. Ele ressaltou que a fala sobre os &ldquo;<em>achacadores<\/em>&rdquo; foi &ldquo;<em>despretensiosa<\/em>&rdquo;.<\/p>\n<p>&ldquo;<em>A minha fala n&atilde;o foi feita em local p&uacute;blico, n&atilde;o &eacute; motivo de proselitismo para mim, n&atilde;o pessoalmente muito menos como ministro de Estado que, sei, devo ter responsabilidades, obriga&ccedil;&otilde;es, uma rela&ccedil;&atilde;o respeitosa e harm&ocirc;nica com os demais companheiros de minist&eacute;rio, com os demais poderes que comp&otilde;em a Rep&uacute;blica<\/em>&rdquo;, disse Cid.<\/p>\n<p><strong>Audi&ecirc;ncia<\/strong><br \/>\nAs primeiras palavras do ministro foram ressaltando sua trajet&oacute;ria pol&iacute;tica como parlamentar no Legislativo e como governador. No Plen&aacute;rio, al&eacute;m dos deputados federais cearenses, est&atilde;o o governador Camilo Santana(<span style=\"font-family: Arial;\">PT<\/span>), o prefeito de Fortaleza, Roberto Cl&aacute;udio(<span style=\"font-family: Arial;\">Pros<\/span>), o presidente do Legislativo estadual, Zezinho Albuquerque(<span style=\"font-family: Arial;\">Pros<\/span>) e o deputado estadual Tin Gomes(<span style=\"font-family: Arial;\">PHS<\/span>).<\/p>\n<p>\n<img loading=\"lazy\" decoding=\"async\" src=\"\/UserFiles\/Image\/politica\/eventos\/cid_ferreira_gomes_camara_federal_18mar2015_465.jpg\" width=\"465\" height=\"311\" align=\"absMiddle\" alt=\"\" \/><\/br> <br \/>\nCid ressaltou que preferiria estar na Casa para tratar sobre temas ligados &agrave; Educa&ccedil;&atilde;o como o Programa Nacional de Educa&ccedil;&atilde;o ou o Fies. Mesmo assim, afirmou que n&atilde;o se furtaria a tratar do tema sobre o qual foi convocado.<\/p>\n<p>\nCid Gomes, apesar de afastado da fun&ccedil;&atilde;o de ministro por motivos de sa&uacute;de, ter&aacute; de explicar, acusa&ccedil;&otilde;es que fez durante palestra em universidade do Par&aacute; em 27 de fevereiro. Cid disse: &ldquo;<em>tem l&aacute; uns 400 deputados, 300 deputados que quanto pior, melhor para eles. Eles querem &eacute; que o governo esteja fr&aacute;gil porque &eacute; a forma de eles achacarem mais, tomarem mais, tirarem mais dele, aprovarem as emendas impositivas<\/em>&rdquo;.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempo de leitura: 14 minutos &quot;Larguem o osso, saiam do governo&quot;, diz Cid a &quot;oportunistas&quot; na C&acirc;mara. Ministro da Educa&ccedil;&atilde;o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[9],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/8253"}],"collection":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/comments?post=8253"}],"version-history":[{"count":0,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/8253\/revisions"}],"wp:attachment":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/media?parent=8253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/categories?post=8253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/tags?post=8253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}