{"id":8303,"date":"2015-04-30T00:00:00","date_gmt":"2015-04-30T00:00:00","guid":{"rendered":""},"modified":"2015-04-30T00:00:00","modified_gmt":"2015-04-30T00:00:00","slug":"Exigencia-de-chip-em-veiculos-comeca-a-valer-daqui-a-2-meses","status":"publish","type":"post","link":"https:\/\/obeabadosertao.com.br\/portal\/2015\/04\/30\/Exigencia-de-chip-em-veiculos-comeca-a-valer-daqui-a-2-meses\/","title":{"rendered":"Exig\u00eancia de chip em ve\u00edculos come\u00e7a a valer daqui a 2 meses"},"content":{"rendered":"<div id=\"tt-temp-estim\">Tempo de leitura: 10 minutos<\/div><p style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\n<span style=\"color: rgb(255, 0, 0);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><em><strong>Entenda o que &eacute; o Siniav, que enviar&aacute; dados do carro ao governo.&nbsp;Detrans pedem adiamento; n&atilde;o est&aacute; claro quem deve arcar com custos.<\/strong><\/em><\/span><\/span><\/span><\/p>\n<p>No pr&oacute;ximo dia 30 de junho come&ccedil;a a valer a obrigatoriedade de que todos os ve&iacute;culos que circulam no Brasil tenham um chip de identifica&ccedil;&atilde;o eletr&ocirc;nica. Por&eacute;m, faltando pouco tempo do fim prazo para instala&ccedil;&atilde;o, apenas o estado de Roraima iniciou &#8211; <em>e parou<\/em> &#8211; a instala&ccedil;&atilde;o, e n&atilde;o h&aacute; uma &quot;<em>corrida<\/em>&quot; para cumprir a exig&ecirc;ncia. Isto porque a data limite deve ser adiada pela segunda vez, a pedido dos Departamentos Estaduais de Tr&acirc;nsito(<span style=\"font-family: Arial;\">Detrans<\/span>).<\/p>\n<p>\nO chip &eacute; o &quot;<em>cora&ccedil;&atilde;o<\/em>&quot; do chamado Sistema Nacional de Identifica&ccedil;&atilde;o de Ve&iacute;culos(<span style=\"font-family: Arial;\">Siniav<\/span>). Ele fica instalada no para-brisa, em uma caixinha semelhante &agrave;s do sistema de cobran&ccedil;a autom&aacute;tica em ped&aacute;gios.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"\/UserFiles\/Image\/automoveis\/chip_automotivo_465.jpg\" width=\"465\" height=\"311\" align=\"absMiddle\" alt=\"\" \/><br \/>\n<span style=\"color: rgb(255, 0, 0);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><em><strong>O Siniav &eacute; formado por chip no ve&iacute;culo, antenas leitoras e sistema que integra dados do Detran.<\/strong><\/em><\/span><\/span><\/span><span style=\"font-family: Verdana;\"><\/p>\n<p>O objetivo do governo federal com o sistema &eacute; melhorar a fiscaliza&ccedil;&atilde;o e a gest&atilde;o do tr&acirc;nsito e da frota. Na pr&aacute;tica, o chip cria uma &quot;<em>placa eletr&ocirc;nica<\/em>&quot; para o carro, enviando informa&ccedil;&otilde;es sobre chassis, ano, modelo e placa por meio de antenas instaladas nas vias.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><\/p>\n<p><span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>Multa a partir de julho<\/strong><\/span><\/span><\/span><br \/>\nEste sistema &eacute; discutido desde 2006. Em 2012, a previs&atilde;o era equipar todos os ve&iacute;culos, incluindo carros, motos, caminh&otilde;es, reboques e m&aacute;quinas agr&iacute;colas, a partir de 1&ordm; de janeiro de 2013. Com o adiamento, o prazo final de implanta&ccedil;&atilde;o vencer&aacute; em 30 de junho pr&oacute;ximo, com aplica&ccedil;&atilde;o de multas a partir de 1&ordm; de julho, conforme a &uacute;ltima resolu&ccedil;&atilde;o do Conselho Nacional de Tr&acirc;nsito(<span style=\"font-family: Arial;\">Contran<\/span>) sobre o tema.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><br \/>\n&nbsp;<br \/>\nNo entanto, com exce&ccedil;&atilde;o de Roraima, nenhum outro estado fez licita&ccedil;&atilde;o para os equipamentos. Ou seja, por mais que o propriet&aacute;rio queira, n&atilde;o &eacute; poss&iacute;vel instalar o chip. Os &oacute;rg&atilde;os respons&aacute;veis pela implanta&ccedil;&atilde;o(<span style=\"font-family: Arial;\">Detrans<\/span>) pediram o adiamento do prazo. Na &uacute;ltima quarta-feira(<span style=\"font-family: Arial;\">29Abril2015<\/span>), representantes de 10 minist&eacute;rios se reuniram no Contran, mas nenhuma altera&ccedil;&atilde;o foi divulgada at&eacute; ent&atilde;o.<\/p>\n<p><span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>Quem paga a conta?<\/strong><\/span><\/span><\/span><br \/>\nA resolu&ccedil;&atilde;o 412 do Contran n&atilde;o determina o quanto nem quem vai arcar com os custos da instala&ccedil;&atilde;o dos chips e dos demais equipamentos do sistema.&nbsp;<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">&ldquo;<em>A maior d&uacute;vida dos Detrans &eacute; o fato de n&atilde;o termos or&ccedil;amento espec&iacute;fico para essa atividade, que tem um custo expressivo porque envolve tecnologia, para chips e torres de monitoramento. N&atilde;o nos mexemos pelas d&uacute;vidas que temos sobre a transfer&ecirc;ncia de um custo para o cidad&atilde;o<\/em>&rdquo;, afirmou Marcos Traad, presidente da Associa&ccedil;&atilde;o Nacional dos Detrans(<span style=\"font-family: Arial;\">AND<\/span>), que s&atilde;o os respons&aacute;veis pela instala&ccedil;&atilde;o.&nbsp;<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">&quot;<em>Se fosse de grande interesse do governo federal implantar o Siniav, ele direcionaria uma parte do or&ccedil;amento para isso<\/em>&quot;, disse Traad.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> O Denatran se limitou a dizer que &ldquo;<em>o processo de implanta&ccedil;&atilde;o do sistema teve in&iacute;cio em todo o territ&oacute;rio nacional em 1&ordm; de janeiro de 2013 e dever&aacute; ser conclu&iacute;do at&eacute; o dia 30 de junho de 2015<\/em>&rdquo;, destacando que a responsabilidade &eacute; dos Detrans e que um poss&iacute;vel adiamento s&oacute; pode ser decidido pelo Contran.<\/p>\n<p>\nSegundo a &uacute;nica empresa homologada at&eacute; meados de abril, a Seagull Tecnologia, com sede no Rio de Janeiro, cada placa eletr&ocirc;nica virgem custa em torno de R$ 40,00 sem contar gastos com infraestrutura de instala&ccedil;&atilde;o, verifica&ccedil;&atilde;o e fiscaliza&ccedil;&atilde;o.&nbsp;&ldquo;<em>Em estados m&eacute;dios podemos estimar em R$ 100,00(<span style=\"font-family: Arial;\">o custo anual do sistema por ve&iacute;culo<\/span>) no primeiro ano e R$ 70,00 nos anos seguintes<\/em>&rdquo;, explicou Mauricio Luz, diretor de tecnologia da empresa.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> Em S&atilde;o Paulo, que possui frota de 26,8 milh&otilde;es de ve&iacute;culos, segundo o pr&oacute;prio Detran, o impacto seria de R$ 2,68 bilh&otilde;es no primeiro ano.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><\/p>\n<p><span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>Roraima cobrou R$ 95,67<\/strong><\/span><\/span><\/span><br \/>\nAt&eacute; agora, apenas o Estado de Roraima iniciou o processo, em janeiro de 2014, mas a instala&ccedil;&atilde;o foi suspensa por meio de decreto legislativo, depois que o Minist&eacute;rio P&uacute;blico estadual abriu investiga&ccedil;&atilde;o sobre suposta cobran&ccedil;a abusiva de R$ 95,67 dos propriet&aacute;rios e por poss&iacute;veis problemas no contrato com a empresa fornecedora dos chips.<\/p>\n<p>\nSegundo o Detran-RR, Francisca Fernandes Silva, de 76 anos, foi a primeira propriet&aacute;ria a instalar o chip no pa&iacute;s. No entanto, ela atualmente roda com o chip no carro sem fun&ccedil;&atilde;o alguma e aguarda a devolu&ccedil;&atilde;o do valor pago. Mas a desinforma&ccedil;&atilde;o &eacute; maior que tudo.<br \/>\n<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"> <br \/>\n&quot;<em>Paguei como todo mundo e dizem que foi cancelado. Hoje em dia a gente n&atilde;o confia mais em nada. Dizem que est&aacute; na Justi&ccedil;a e que v&atilde;o devolver o dinheiro, mas at&eacute; agora ningu&eacute;m recebeu nada. Parece que era trambique<\/em>&quot;, afirmou.<\/p>\n<p>\nDe acordo com o Detran-RR, para ter o ressarcimento do valor, o contribuinte deve protocolar um formul&aacute;rio com os dados do ve&iacute;culo. O pedido ser&aacute; analisado pelo administrativo do &oacute;rg&atilde;o e em seguida ser&aacute; feita a devolu&ccedil;&atilde;o da quantia ao propriet&aacute;rio do ve&iacute;culo.<\/p>\n<p><span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>De onde v&ecirc;m os chips<\/strong><\/span><\/span><\/span><br \/>\nO Detran-SP aponta que o fato de apenas uma empresa estar homologada para fornecer os equipamentos do Siniav, por ora, &quot;<em>inviabiliza a concorr&ecirc;ncia em uma eventual licita&ccedil;&atilde;o p&uacute;blica, fundamental para reduzir os custos de implanta&ccedil;&atilde;o do sistema e, consequentemente, os custos para o cidad&atilde;o<\/em><em>(<span style=\"font-family: Arial;\">que ter&aacute; de adquirir o chip<\/span>)&quot;<\/em>.<br \/>\n<\/span><\/span><br \/>\n<img decoding=\"async\" src=\"\/UserFiles\/Image\/automoveis\/chip_automotivo_radar_465.jpg\" width=\"465\" height=\"311\" align=\"absMiddle\" alt=\"\" style=\"font-size: small;\" \/><span style=\"font-size: small;\"><br \/>\n<\/span><strong style=\"color: rgb(255, 0, 0); font-family: Arial; font-size: medium;\">No mundo: 1,5 Trilh&atilde;o. Esse &eacute; o mercado para cidades conectadas em 2020.<\/strong><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\"><\/p>\n<p>O Denatran diz que uma segunda empresa est&aacute; em processo de homologa&ccedil;&atilde;o e uma terceira, em fase de certifica&ccedil;&atilde;o, para viabilizar as licita&ccedil;&otilde;es em cada estado.&nbsp;<\/span><\/span><span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">A Seagull afirma que j&aacute; investiu R$ 25 milh&otilde;es no sistema em 5 anos e acumula um custo mensal fixo de R$ 400 mil no projeto, e reclama da falta de divulga&ccedil;&atilde;o da regra.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><br \/>\n&ldquo;<em>N&atilde;o houve comprometimento do governo federal, nem mesmo uma divulga&ccedil;&atilde;o adequada. Em reuni&atilde;o da AND, a maioria dos diretores de tr&acirc;nsito que assumiram recentemente n&atilde;o sabia da exist&ecirc;ncia do Siniav<\/em>&rdquo;, o diretor de tecnologia.<\/p>\n<p><span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>Como funciona?<\/strong><\/span><\/span><\/span><br \/>\nO sistema consiste na identifica&ccedil;&atilde;o de ve&iacute;culos por radiofrequ&ecirc;ncia, por meio do chip instalado no para-brisa. Sem uso de GPS, a leitura da &ldquo;<em>placa eletr&ocirc;nica<\/em>&rdquo; &eacute; feita apenas por meio de antenas ou totens, exatamente o mesmo sistema usado no pagamento de ped&aacute;gio eletr&ocirc;nico nas estradas.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><br \/>\nConforme os par&acirc;metros do Siniav, o chip carregar&aacute; informa&ccedil;&otilde;es criptografadas sobre chassis, ano, modelo e placa. Segundo o Denatran, o Registro Nacional de Ve&iacute;culos(<span style=\"font-family: Arial;\">Renavam<\/span>) e informa&ccedil;&otilde;es pessoais do propriet&aacute;rio ser&atilde;o mantidos em sigilo.<\/p>\n<p>\nAs antenas devem ser instaladas em pontos estrat&eacute;gicos nas cidades, para captar as informa&ccedil;&otilde;es sobre ve&iacute;culos no momento que passarem pr&oacute;ximos. A localiza&ccedil;&atilde;o do ve&iacute;culo n&atilde;o poder&aacute; ser determinada exatamente, a n&atilde;o ser quando ele estiver passando por um leitor, mas diversas antenas ser&atilde;o capazes de triangular as informa&ccedil;&otilde;es e apontar a dire&ccedil;&atilde;o do ve&iacute;culo.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><br \/>\nDe acordo com o Denatran, o sistema central, que reunir&aacute; os dados vindos de todos os estados j&aacute; est&aacute; pronto para operar. &quot;<em>O que falta &eacute; a integra&ccedil;&atilde;o dos Detrans dos estados ao sistema<\/em>&quot;, explicou o Minist&eacute;rio das Cidades.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><\/p>\n<p><span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>Efeitos pr&aacute;ticos<\/strong><\/span><\/span><\/span><br \/>\nDo lado dos estados, o interesse no Siniav vem basicamente com a possibilidade de elevar a arrecada&ccedil;&atilde;o com cobran&ccedil;as de licenciamento, IPVA e multas. No Distrito Federal, por exemplo, cerca de 30% da frota de 1,5 milh&atilde;o de ve&iacute;culos em circula&ccedil;&atilde;o no final de 2014 n&atilde;o pagou o licenciamento.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><br \/>\nAl&eacute;m disso, ser&aacute; poss&iacute;vel automatizar o pagamento de estacionamentos p&uacute;blicos e melhorar o tr&atilde;nsito: por exemplo, antenas pr&oacute;ximas a sem&aacute;foros poderiam indicar qual sentido tem o maior fluxo e deixar o sinal aberto por mais tempo, para reduzir o congestionamento.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><br \/>\nNa parte de seguran&ccedil;a, a localiza&ccedil;&atilde;o carros roubados ou clonados, se estes passarem perto de alguma antena, &eacute; uma das possibilidades, mas n&atilde;o h&aacute; rastreamento por GPS, nem mesmo bloqueio remoto. Um sistema semelhante previsto pelo Contran, por&eacute;m com rastreamento, foi barrado na Justi&ccedil;a por ser considerado uma amea&ccedil;a &agrave; privacidade.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><br \/>\nDe acordo com Dario Sassi Thober, presidente do instituto Wernher von Braun, que desenvolveu o sistema do Siniav junto ao Denatran, toda parte de tecnologia est&aacute; pronta. &ldquo;<em>Pode ser implementado muito rapidamente, bastando definir responsabilidades e agentes em &acirc;mbito nacional<\/em>&rdquo;, afirmou.<\/p>\n<p><\/span><\/span><span style=\"color: rgb(0, 0, 255);\"><span style=\"font-size: medium;\"><span style=\"font-family: Arial;\"><strong>Neg&oacute;cios<\/strong><\/span><\/span><\/span><br \/>\n<span style=\"font-size: small;\"><span style=\"font-family: Verdana;\">O modelo seria um passo rumo &agrave; tend&ecirc;ncia chamada de &ldquo;<em>cidades conectadas<\/em>&rdquo;, um mercado de US$ 1,5 trilh&atilde;o em 2020 no mundo inteiro, segundo proje&ccedil;&atilde;o da consultoria de mercado Frost &amp; Sullivan.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><br \/>\nA regulamenta&ccedil;&atilde;o do Siniav tamb&eacute;m prev&ecirc; o uso da tecnologia por empresas particulares, em conv&ecirc;nio com o Denatran, se for de interesse p&uacute;blico, por exemplo, para rastreamento de cargas, controle de frotas, ou cobran&ccedil;a de ped&aacute;gio por trecho percorrido, entre outras funcionalidades.<\/p>\n<p>\nNa regi&atilde;o de Campinas(<span style=\"font-family: Arial;\">SP<\/span>), concession&aacute;rias de rodovias j&aacute; utilizam sistema similar para cobran&ccedil;a de ped&aacute;gio por trecho percorrido, com antenas, sem postos de parada. Segundo Thober, o volume de transa&ccedil;&otilde;es eletr&ocirc;nicas na regi&atilde;o &eacute; um dos maiores do mundo dentro do sistema de identifica&ccedil;&atilde;o por radiofrequ&ecirc;ncia.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><br \/>\n&ldquo;<em>Existe mercado no Brasil? Sim. Em termos de maturidade, ainda est&aacute; engatinhando. O chip seria um passo bastante importante para os carros conectados, e tem tamb&eacute;m aplica&ccedil;&otilde;es para transporte p&uacute;blico. Fica mais f&aacute;cil implantar &#8216;car sharing'(<span style=\"font-family: Arial;\">compartilhamento<\/span>), por exemplo<\/em>&rdquo;, apontou Marise Luca, diretora de solu&ccedil;&otilde;es de transporte da Ericsson na Am&eacute;rica Latina. A empresa desenvolve sistemas para carros e &ocirc;nibus conectados com a Volvo.<\/span><\/span><br \/>\n<span style=\"font-size: small;\"><br \/>\n<span style=\"font-family: Verdana;\"><br \/>\nDe acordo com Thober, a tecnologia de identifica&ccedil;&atilde;o por radiofrequ&ecirc;ncia j&aacute; &eacute; utilizada para a identifica&ccedil;&atilde;o em todos os continentes. No M&eacute;xico, por exemplo, chips chegam a ser usados em pessoas, para evitar sequestros. O sistema tamb&eacute;m &eacute; usado para monitorar mercadorias ou para restringir a entrada e sa&iacute;da de pessoas em lugares restritos.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempo de leitura: 10 minutos Entenda o que &eacute; o Siniav, que enviar&aacute; dados do carro ao governo.&nbsp;Detrans pedem adiamento; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[9],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/8303"}],"collection":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/comments?post=8303"}],"version-history":[{"count":0,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/posts\/8303\/revisions"}],"wp:attachment":[{"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/media?parent=8303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/categories?post=8303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obeabadosertao.com.br\/portal\/wp-json\/wp\/v2\/tags?post=8303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}